{"id":30,"count":31,"description":"Descubre libros solidarios que acercan historias de cooperaci\u00f3n, igualdad y transformaci\u00f3n social.\r\n\r\nEncontrar\u00e1s t\u00edtulos como \u201cLa revoluci\u00f3n de las agujas\u201d, que relata la historia de Isabel Mart\u00edn y de las mujeres de Creative Handicrafts, as\u00ed como cuentos infantiles solidarios creados junto a estudiantes de la Universidad de Zaragoza.\r\n\r\nCada compra contribuye a apoyar proyectos de cooperaci\u00f3n internacional y acci\u00f3n social impulsados por Fundaci\u00f3n Isabel Mart\u00edn.","link":"https:\/\/fundacionisabelmartin.es\/tienda\/categoria-producto\/libros\/","name":"Libros","slug":"libros","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LibrosLibros solidarios | Fundaci\u00f3n Isabel Mart\u00edn<\/title>\n<meta name=\"description\" content=\"Libros y cuentos solidarios sobre Creative Handicrafts, cuentos infantiles solidarios y cuentos en ingl\u00e9s de alumnos\/as de la Universidad de Zaragoza.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fundacionisabelmartin.es\/tienda\/categoria-producto\/libros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LibrosLibros solidarios | Fundaci\u00f3n Isabel Mart\u00edn\" \/>\n<meta property=\"og:description\" content=\"Libros y cuentos solidarios sobre Creative Handicrafts, cuentos infantiles solidarios y cuentos en ingl\u00e9s de alumnos\/as de la Universidad de Zaragoza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fundacionisabelmartin.es\/tienda\/categoria-producto\/libros\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n Isabel Mart\u00edn Tienda\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fundacionisabelmartin.es\/tienda\/wp-content\/uploads\/2018\/04\/para-post-carlos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1181\" \/>\n\t<meta property=\"og:image:height\" content=\"787\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ongisabelmartin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/fundacionisabelmartin.es\\\/tienda\\\/categoria-producto\\\/libros\\\/\",\"url\":\"https:\\\/\\\/fundacionisabelmartin.es\\\/tienda\\\/categoria-producto\\\/libros\\\/\",\"name\":\"LibrosLibros solidarios | Fundaci\u00f3n Isabel Mart\u00edn\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionisabelmartin.es\\\/tienda\\\/#website\"},\"description\":\"Libros y cuentos solidarios sobre Creative Handicrafts, cuentos infantiles solidarios y cuentos en ingl\u00e9s de alumnos\\\/as de la Universidad de Zaragoza.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fundacionisabelmartin.es\\\/tienda\\\/categoria-producto\\\/libros\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fundacionisabelmartin.es\\\/tienda\\\/categoria-producto\\\/libros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/fundacionisabelmartin.es\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Libros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fundacionisabelmartin.es\\\/tienda\\\/#website\",\"url\":\"https:\\\/\\\/fundacionisabelmartin.es\\\/tienda\\\/\",\"name\":\"FUNDACI\u00d3N ISABEL MARTIN | TIENDA\",\"description\":\"La tienda de la Fundaci\u00f3n Isabel Mart\u00edn ofrece productos de Comercio Justo y Solidarios con el objetivo de financiar los proyectos de Cooperaci\u00f3n al Desarrollo que financiamos en varios pa\u00edses del sur, centrados en el empoderamiento de las mujeres y la infancia desprotegida.\",\"publisher\":{\"@id\":\"https:\\\/\\\/fundacionisabelmartin.es\\\/tienda\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fundacionisabelmartin.es\\\/tienda\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fundacionisabelmartin.es\\\/tienda\\\/#organization\",\"name\":\"Fundaci\u00f3n Isabel Mart\u00edn\",\"url\":\"https:\\\/\\\/fundacionisabelmartin.es\\\/tienda\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fundacionisabelmartin.es\\\/tienda\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fundacionisabelmartin.es\\\/tienda\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/ISABEL-MARTIN-LOGO-FINAL.png\",\"contentUrl\":\"https:\\\/\\\/fundacionisabelmartin.es\\\/tienda\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/ISABEL-MARTIN-LOGO-FINAL.png\",\"width\":1153,\"height\":496,\"caption\":\"Fundaci\u00f3n Isabel Mart\u00edn\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacionisabelmartin.es\\\/tienda\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OngIsabelMartin\",\"https:\\\/\\\/x.com\\\/ongisabelmartin\",\"https:\\\/\\\/fundacionisabelmartin.es\\\/tienda\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/10593946\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCibqwKMVjaAmuWXoBF3edkQ\",\"https:\\\/\\\/www.instagram.com\\\/ongisabelmartin\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LibrosLibros solidarios | Fundaci\u00f3n Isabel Mart\u00edn","description":"Libros y cuentos solidarios sobre Creative Handicrafts, cuentos infantiles solidarios y cuentos en ingl\u00e9s de alumnos\/as de la Universidad de Zaragoza.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fundacionisabelmartin.es\/tienda\/categoria-producto\/libros\/","og_locale":"es_ES","og_type":"article","og_title":"LibrosLibros solidarios | Fundaci\u00f3n Isabel Mart\u00edn","og_description":"Libros y cuentos solidarios sobre Creative Handicrafts, cuentos infantiles solidarios y cuentos en ingl\u00e9s de alumnos\/as de la Universidad de Zaragoza.","og_url":"https:\/\/fundacionisabelmartin.es\/tienda\/categoria-producto\/libros\/","og_site_name":"Fundaci\u00f3n Isabel Mart\u00edn Tienda","og_image":[{"width":1181,"height":787,"url":"https:\/\/fundacionisabelmartin.es\/tienda\/wp-content\/uploads\/2018\/04\/para-post-carlos.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ongisabelmartin","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/fundacionisabelmartin.es\/tienda\/categoria-producto\/libros\/","url":"https:\/\/fundacionisabelmartin.es\/tienda\/categoria-producto\/libros\/","name":"LibrosLibros solidarios | Fundaci\u00f3n Isabel Mart\u00edn","isPartOf":{"@id":"https:\/\/fundacionisabelmartin.es\/tienda\/#website"},"description":"Libros y cuentos solidarios sobre Creative Handicrafts, cuentos infantiles solidarios y cuentos en ingl\u00e9s de alumnos\/as de la Universidad de Zaragoza.","breadcrumb":{"@id":"https:\/\/fundacionisabelmartin.es\/tienda\/categoria-producto\/libros\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/fundacionisabelmartin.es\/tienda\/categoria-producto\/libros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fundacionisabelmartin.es\/tienda\/"},{"@type":"ListItem","position":2,"name":"Libros"}]},{"@type":"WebSite","@id":"https:\/\/fundacionisabelmartin.es\/tienda\/#website","url":"https:\/\/fundacionisabelmartin.es\/tienda\/","name":"FUNDACI\u00d3N ISABEL MARTIN | TIENDA","description":"La tienda de la Fundaci\u00f3n Isabel Mart\u00edn ofrece productos de Comercio Justo y Solidarios con el objetivo de financiar los proyectos de Cooperaci\u00f3n al Desarrollo que financiamos en varios pa\u00edses del sur, centrados en el empoderamiento de las mujeres y la infancia desprotegida.","publisher":{"@id":"https:\/\/fundacionisabelmartin.es\/tienda\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fundacionisabelmartin.es\/tienda\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fundacionisabelmartin.es\/tienda\/#organization","name":"Fundaci\u00f3n Isabel Mart\u00edn","url":"https:\/\/fundacionisabelmartin.es\/tienda\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fundacionisabelmartin.es\/tienda\/#\/schema\/logo\/image\/","url":"https:\/\/fundacionisabelmartin.es\/tienda\/wp-content\/uploads\/2018\/04\/ISABEL-MARTIN-LOGO-FINAL.png","contentUrl":"https:\/\/fundacionisabelmartin.es\/tienda\/wp-content\/uploads\/2018\/04\/ISABEL-MARTIN-LOGO-FINAL.png","width":1153,"height":496,"caption":"Fundaci\u00f3n Isabel Mart\u00edn"},"image":{"@id":"https:\/\/fundacionisabelmartin.es\/tienda\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OngIsabelMartin","https:\/\/x.com\/ongisabelmartin","https:\/\/fundacionisabelmartin.es\/tienda","https:\/\/www.linkedin.com\/company\/10593946","https:\/\/www.youtube.com\/channel\/UCibqwKMVjaAmuWXoBF3edkQ","https:\/\/www.instagram.com\/ongisabelmartin\/"]}]}},"_links":{"self":[{"href":"https:\/\/fundacionisabelmartin.es\/tienda\/wp-json\/wp\/v2\/product_cat\/30","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundacionisabelmartin.es\/tienda\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/fundacionisabelmartin.es\/tienda\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/fundacionisabelmartin.es\/tienda\/wp-json\/wp\/v2\/product?product_cat=30"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}